{"id":22959,"date":"2016-08-20T17:04:00","date_gmt":"2016-08-20T16:04:00","guid":{"rendered":"https:\/\/www.bestofrome.fr\/la-cannoleria-siciliana\/"},"modified":"2025-04-01T15:29:20","modified_gmt":"2025-04-01T14:29:20","slug":"la-cannoleria-siciliana","status":"publish","type":"post","link":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/","title":{"rendered":"La Cannoleria Siciliana"},"content":{"rendered":"<p>La <strong>Cannoleria Siciliana<\/strong> \u00e8 una pasticceria siciliana di buona reputazione, presente in tre quartieri di Roma: Prati, Piazza de Re di Roma e Corso Trieste.<br \/>\nSpecializzata in cannoli con sapori come cioccolato o pistacchio per la pasticceria, offre anche piatti salati come gli arancini, oltre a prodotti artigianali siciliani come pasta e pesto, o gelati artigianali.<br \/>\n\u00c8 aperto tutti i giorni dalle 7:00 all&#8217;1:00 e fino alle 2:00 il venerd\u00ec e il sabato<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-17824\" src=\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg\" alt=\"cannoleria-siciliana-logo-roma\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg 300w, https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma-150x84.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Cannoleria Siciliana<\/strong><br \/>\n<em>Piazzale degli Eroi, 24, 00192 Roma &#8211; Piazza dei Re di Roma, 10, 00183 Roma &#8211; Corso Trieste, 100, 00198 Roma <\/em><br \/>\n<a href=\"https:\/\/www.lacannoleriasiciliana.it\/\" target=\"_blank\" rel=\"noopener\">www.lacannoleriasiciliana.it<\/a><\/p>\n<div id=\"cttm-shortcode-helper\"><div id=\"travelersmap-container-6a045e836f88e\" class=\"travelersmap-container\" style=\"z-index: 1; min-height: 10px; min-width:10px; height:400px;width:100%; max-width:; max-height:; position:relative;\"><div style=\"position:absolute; z-index:-1;top: 50%;text-align: center;display: block;left: 50%;transform: translate(-50%,-50%);\">Travelers' Map is loading... <br> If you see this after your page is loaded completely, leafletJS files are missing.<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La <strong>Cannoleria Siciliana<\/strong> si trova in tre indirizzi di Roma (Prati, Re di Roma e Corso Trieste), specializzata nella pasticceria siciliana, in particolare dei cannoli, proponendo anche prodotti artigianali della Sicilia, tra cui pasta e pesto, e piatti salati come gli arancini. [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":21268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[604,606,608],"tags":[715],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Cannoleria Siciliana - Visita di Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Cannoleria Siciliana - Visita di Roma\" \/>\n<meta property=\"og:description\" content=\"La Cannoleria Siciliana si trova in tre indirizzi di Roma (Prati, Re di Roma e Corso Trieste), specializzata nella pasticceria siciliana, in particolare dei cannoli, proponendo anche prodotti artigianali della Sicilia, tra cui pasta e pesto, e piatti salati come gli arancini. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/\" \/>\n<meta property=\"og:site_name\" content=\"Visita di Roma\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-20T16:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T14:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9sar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#organization\",\"name\":\"Bestofrome.fr\",\"url\":\"https:\/\/www.bestofrome.fr\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2025\/11\/logo512bestofrome.png\",\"contentUrl\":\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2025\/11\/logo512bestofrome.png\",\"width\":512,\"height\":512,\"caption\":\"Bestofrome.fr\"},\"image\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#website\",\"url\":\"https:\/\/www.bestofrome.fr\/it\/\",\"name\":\"Visita di Roma\",\"description\":\"Tutto per scoprire Roma\",\"publisher\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bestofrome.fr\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg\",\"contentUrl\":\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg\",\"width\":300,\"height\":168},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#webpage\",\"url\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/\",\"name\":\"La Cannoleria Siciliana - Visita di Roma\",\"isPartOf\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#primaryimage\"},\"datePublished\":\"2016-08-20T16:04:00+00:00\",\"dateModified\":\"2025-04-01T14:29:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.bestofrome.fr\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Cannoleria Siciliana\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#\/schema\/person\/f611766d26241b06cbcf4eac35cf8825\"},\"headline\":\"La Cannoleria Siciliana\",\"datePublished\":\"2016-08-20T16:04:00+00:00\",\"dateModified\":\"2025-04-01T14:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#webpage\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg\",\"keywords\":[\"Pane e pasticceria\"],\"articleSection\":[\"Idee e buoni indirizzi, la nostra Roma\",\"Panifici e pasticcerie preferiti a Roma\",\"Pizza al taglio e cibo di strada : buoni indirizzi a Roma\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#\/schema\/person\/f611766d26241b06cbcf4eac35cf8825\",\"name\":\"C\\u00e9sar\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bestofrome.fr\/it\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5c3162350047f03c6a1083f7f2185e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5c3162350047f03c6a1083f7f2185e7?s=96&d=mm&r=g\",\"caption\":\"C\\u00e9sar\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Cannoleria Siciliana - Visita di Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/","og_locale":"it_IT","og_type":"article","og_title":"La Cannoleria Siciliana - Visita di Roma","og_description":"La Cannoleria Siciliana si trova in tre indirizzi di Roma (Prati, Re di Roma e Corso Trieste), specializzata nella pasticceria siciliana, in particolare dei cannoli, proponendo anche prodotti artigianali della Sicilia, tra cui pasta e pesto, e piatti salati come gli arancini. [...]","og_url":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/","og_site_name":"Visita di Roma","article_published_time":"2016-08-20T16:04:00+00:00","article_modified_time":"2025-04-01T14:29:20+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg","type":"image\/jpeg"}],"twitter_misc":{"Scritto da":"C\u00e9sar","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.bestofrome.fr\/it\/#organization","name":"Bestofrome.fr","url":"https:\/\/www.bestofrome.fr\/it\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.bestofrome.fr\/it\/#logo","inLanguage":"it-IT","url":"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2025\/11\/logo512bestofrome.png","contentUrl":"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2025\/11\/logo512bestofrome.png","width":512,"height":512,"caption":"Bestofrome.fr"},"image":{"@id":"https:\/\/www.bestofrome.fr\/it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.bestofrome.fr\/it\/#website","url":"https:\/\/www.bestofrome.fr\/it\/","name":"Visita di Roma","description":"Tutto per scoprire Roma","publisher":{"@id":"https:\/\/www.bestofrome.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bestofrome.fr\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg","contentUrl":"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg","width":300,"height":168},{"@type":"WebPage","@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#webpage","url":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/","name":"La Cannoleria Siciliana - Visita di Roma","isPartOf":{"@id":"https:\/\/www.bestofrome.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#primaryimage"},"datePublished":"2016-08-20T16:04:00+00:00","dateModified":"2025-04-01T14:29:20+00:00","breadcrumb":{"@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bestofrome.fr\/it\/"},{"@type":"ListItem","position":2,"name":"La Cannoleria Siciliana"}]},{"@type":"Article","@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#article","isPartOf":{"@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#webpage"},"author":{"@id":"https:\/\/www.bestofrome.fr\/it\/#\/schema\/person\/f611766d26241b06cbcf4eac35cf8825"},"headline":"La Cannoleria Siciliana","datePublished":"2016-08-20T16:04:00+00:00","dateModified":"2025-04-01T14:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#webpage"},"wordCount":100,"commentCount":0,"publisher":{"@id":"https:\/\/www.bestofrome.fr\/it\/#organization"},"image":{"@id":"https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bestofrome.fr\/wp-content\/uploads\/2016\/08\/cannoleria-siciliana-logo-roma.jpg","keywords":["Pane e pasticceria"],"articleSection":["Idee e buoni indirizzi, la nostra Roma","Panifici e pasticcerie preferiti a Roma","Pizza al taglio e cibo di strada : buoni indirizzi a Roma"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bestofrome.fr\/it\/la-cannoleria-siciliana\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.bestofrome.fr\/it\/#\/schema\/person\/f611766d26241b06cbcf4eac35cf8825","name":"C\u00e9sar","image":{"@type":"ImageObject","@id":"https:\/\/www.bestofrome.fr\/it\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/e5c3162350047f03c6a1083f7f2185e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5c3162350047f03c6a1083f7f2185e7?s=96&d=mm&r=g","caption":"C\u00e9sar"}}]}},"_links":{"self":[{"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/posts\/22959"}],"collection":[{"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/comments?post=22959"}],"version-history":[{"count":4,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/posts\/22959\/revisions"}],"predecessor-version":[{"id":28083,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/posts\/22959\/revisions\/28083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/media\/21268"}],"wp:attachment":[{"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/media?parent=22959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/categories?post=22959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bestofrome.fr\/it\/wp-json\/wp\/v2\/tags?post=22959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}